{"id":3269,"date":"2024-01-22T13:53:03","date_gmt":"2024-01-22T12:53:03","guid":{"rendered":"https:\/\/linmot.com\/it\/?p=3269"},"modified":"2024-09-11T09:40:42","modified_gmt":"2024-09-11T07:40:42","slug":"investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot","status":"publish","type":"post","link":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/","title":{"rendered":"Investire nel vostro futuro &#8211; Il nuovo centro di ricerca e sviluppo LinMot"},"content":{"rendered":"<p><strong>Siamo lieti di poter condividere con voi una notizia entusiasmante: Il modernissimo Centro di Ricerca e Sviluppo LinMot \u00e8 stato completato con successo. Questo investimento sottolinea il nostro costante impegno verso l&#8217;innovazione e l&#8217;eccellenza tecnologica e il nostro sforzo per superare le aspettative dei nostri clienti e contribuire in modo duraturo al progresso tecnologico attraverso la ricerca e lo sviluppo continui.<\/strong><\/p>\n<hr \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5251 size-full\" src=\"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/neues-forschungs-und-entwicklungsgebaeude-two.jpg\" alt=\"\" width=\"1000\" height=\"667\" \/>\n<hr \/>\n<p>Il centro, recentemente completato, \u00e8 stato progettato per sviluppare tecnologie pionieristiche e soluzioni avanzate nel campo dei motori lineari. Con strutture di laboratorio all&#8217;avanguardia e professionisti altamente qualificati, offre spazio a team interdisciplinari per favorire la collaborazione e lo scambio di idee. L&#8217;importanza del Centro di Ricerca e Sviluppo LinMot \u00e8 sottolineata da diversi fattori chiave:<\/p>\n<p>\u2022 <strong>Leadership tecnologica<\/strong>: dal 1993 LinMot \u00e8 pioniere nello sviluppo e nella produzione di motori lineari di alta precisione. Il centro consolida questa posizione creando uno spazio per lo sviluppo di tecnologie innovative che soddisfino le esigenze di un panorama industriale in continua evoluzione.<\/p>\n<p>\u2022 <strong>Soluzioni personalizzate<\/strong>: LinMot si \u00e8 costruita una reputazione per le soluzioni personalizzate che coprono un&#8217;ampia gamma di applicazioni. Il nuovo centro consentir\u00e0 all&#8217;azienda di affinare ulteriormente le proprie capacit\u00e0 e di soddisfare in modo ancora pi\u00f9 preciso le esigenze specifiche dei clienti.<\/p>\n<p>\u2022 <strong>Attrazione e sviluppo dei talenti<\/strong>: LinMot ha sempre investito in professionisti di talento. Il centro funge da polo di innovazione per attrarre e sviluppare i migliori talenti. In questo modo LinMot continua a riunire le migliori menti del settore e contribuisce allo sviluppo di tecnologie che superano i confini del proprio settore.<\/p>\n<p>\u2022 <strong>Tecnologie rispettose dell&#8217;ambiente<\/strong>: LinMot \u00e8 impegnata in tecnologie rispettose dell&#8217;ambiente. Il centro si concentrer\u00e0 sullo sviluppo di soluzioni ad alta efficienza energetica per ridurre al minimo l&#8217;impronta ambientale dei prodotti fabbricati.<\/p>\n<p>Per ulteriori approfondimenti, annunci e storie dal mondo della tecnologia dei motori lineari, seguiteci qui o su LinkedIn e rimanete aggiornati con noi. Attendiamo con ansia gli entusiasmanti sviluppi che questo centro porter\u00e0 nel campo dei motori lineari!<\/p>\n<hr \/>\n<div class=\"carousel slide\" id=\"c6dcc43f0fded0bceab893a28e686c97\" data-ride=\"carousel\">  <div class=\"carousel-inner\" role=\"listbox\">    <div class=\"item active\">      <img decoding=\"async\" src=\"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2024\/01\/neues-forschung-und-entwicklungsgebaeude-four.jpg\" alt=\"...\">    <\/div>    <div class=\"item\">      <img decoding=\"async\" src=\"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2024\/01\/neues-forschung-und-entwicklungsgebaeude-main.jpg\" alt=\"...\">    <\/div>    <div class=\"item\">      <img decoding=\"async\" src=\"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2024\/01\/neues-forschung-und-entwicklungsgebaeude-one.jpg\" alt=\"...\">    <\/div>    <div class=\"item\">      <img decoding=\"async\" src=\"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2024\/01\/neues-forschung-und-entwicklungsgebaeude-three.jpg\" alt=\"...\">    <\/div>  <\/div><div class=\"navigation\"><a class=\"left carousel-control\" href=\"#c6dcc43f0fded0bceab893a28e686c97\" role=\"button\" data-slide=\"prev\"><\/a><a class=\"right carousel-control\" href=\"#c6dcc43f0fded0bceab893a28e686c97\" role=\"button\" data-slide=\"next\"><\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Siamo lieti di poter condividere con voi una notizia entusiasmante: Il modernissimo Centro di Ricerca e Sviluppo LinMot \u00e8 stato completato con successo. Questo investimento sottolinea il nostro costante impegno verso l&#8217;innovazione e l&#8217;eccellenza tecnologica e il nostro sforzo per superare le aspettative dei nostri clienti e contribuire in modo duraturo al progresso tecnologico attraverso [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-3269","post","type-post","status-publish","format-standard","hentry","category-articolo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Investire nel vostro futuro - Il nuovo centro di ricerca e sviluppo LinMot<\/title>\n<meta name=\"description\" content=\"Siamo lieti di poter condividere con voi una notizia entusiasmante: Il modernissimo Centro di Ricerca e Sviluppo LinMot \u00e8 stato completato con successo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investire nel vostro futuro - Il nuovo centro di ricerca e sviluppo LinMot\" \/>\n<meta property=\"og:description\" content=\"Siamo lieti di poter condividere con voi una notizia entusiasmante: Il modernissimo Centro di Ricerca e Sviluppo LinMot \u00e8 stato completato con successo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/\" \/>\n<meta property=\"og:site_name\" content=\"LinMot e MagSpring - Italiano\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-22T12:53:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T07:40:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2024\/01\/neues-forschung-und-entwicklungsgebaeude-four.jpg\" \/>\n<meta name=\"author\" content=\"andreas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"andreas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"TechArticle\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/\"},\"author\":{\"name\":\"andreas\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#\\\/schema\\\/person\\\/c38ac16ef20d42812ab8395e98452df0\"},\"headline\":\"Investire nel vostro futuro &#8211; Il nuovo centro di ricerca e sviluppo LinMot\",\"datePublished\":\"2024-01-22T12:53:03+00:00\",\"dateModified\":\"2024-09-11T07:40:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/\"},\"wordCount\":332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/linmot.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/01\\\/neues-forschungs-und-entwicklungsgebaeude-two.jpg\",\"articleSection\":[\"Articolo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/\",\"url\":\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/\",\"name\":\"Investire nel vostro futuro - Il nuovo centro di ricerca e sviluppo LinMot\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/linmot.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/01\\\/neues-forschungs-und-entwicklungsgebaeude-two.jpg\",\"datePublished\":\"2024-01-22T12:53:03+00:00\",\"dateModified\":\"2024-09-11T07:40:42+00:00\",\"description\":\"Siamo lieti di poter condividere con voi una notizia entusiasmante: Il modernissimo Centro di Ricerca e Sviluppo LinMot \u00e8 stato completato con successo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/#primaryimage\",\"url\":\"https:\\\/\\\/linmot.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/01\\\/neues-forschungs-und-entwicklungsgebaeude-two.jpg\",\"contentUrl\":\"https:\\\/\\\/linmot.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/01\\\/neues-forschungs-und-entwicklungsgebaeude-two.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/blog\\\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/linmot.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investire nel vostro futuro &#8211; Il nuovo centro di ricerca e sviluppo LinMot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/linmot.com\\\/it\\\/\",\"name\":\"LinMot e MagSpring - Italiano\",\"description\":\"Motori lineari e sistemi di motori lineari di alta qualit\u00e0\",\"publisher\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linmot.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#organization\",\"name\":\"NTI AG - LinMot & MagSpring\",\"url\":\"https:\\\/\\\/linmot.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/linmot.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/05\\\/linmot-social-share-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/linmot.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/05\\\/linmot-social-share-logo.jpg\",\"width\":800,\"height\":500,\"caption\":\"NTI AG - LinMot & MagSpring\"},\"image\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pamoco-spa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/LinMotEurope\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#\\\/schema\\\/person\\\/c38ac16ef20d42812ab8395e98452df0\",\"name\":\"andreas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99f323d000f2404dd6db188993d585a3765965ba46a2313d331baea8a979d2e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99f323d000f2404dd6db188993d585a3765965ba46a2313d331baea8a979d2e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e99f323d000f2404dd6db188993d585a3765965ba46a2313d331baea8a979d2e?s=96&d=mm&r=g\",\"caption\":\"andreas\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Investire nel vostro futuro - Il nuovo centro di ricerca e sviluppo LinMot","description":"Siamo lieti di poter condividere con voi una notizia entusiasmante: Il modernissimo Centro di Ricerca e Sviluppo LinMot \u00e8 stato completato con successo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/","og_locale":"it_IT","og_type":"article","og_title":"Investire nel vostro futuro - Il nuovo centro di ricerca e sviluppo LinMot","og_description":"Siamo lieti di poter condividere con voi una notizia entusiasmante: Il modernissimo Centro di Ricerca e Sviluppo LinMot \u00e8 stato completato con successo.","og_url":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/","og_site_name":"LinMot e MagSpring - Italiano","article_published_time":"2024-01-22T12:53:03+00:00","article_modified_time":"2024-09-11T07:40:42+00:00","og_image":[{"url":"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2024\/01\/neues-forschung-und-entwicklungsgebaeude-four.jpg","type":"","width":"","height":""}],"author":"andreas","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"andreas","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/#article","isPartOf":{"@id":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/"},"author":{"name":"andreas","@id":"https:\/\/linmot.com\/it\/#\/schema\/person\/c38ac16ef20d42812ab8395e98452df0"},"headline":"Investire nel vostro futuro &#8211; Il nuovo centro di ricerca e sviluppo LinMot","datePublished":"2024-01-22T12:53:03+00:00","dateModified":"2024-09-11T07:40:42+00:00","mainEntityOfPage":{"@id":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/"},"wordCount":332,"commentCount":0,"publisher":{"@id":"https:\/\/linmot.com\/it\/#organization"},"image":{"@id":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/#primaryimage"},"thumbnailUrl":"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/neues-forschungs-und-entwicklungsgebaeude-two.jpg","articleSection":["Articolo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/","url":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/","name":"Investire nel vostro futuro - Il nuovo centro di ricerca e sviluppo LinMot","isPartOf":{"@id":"https:\/\/linmot.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/#primaryimage"},"image":{"@id":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/#primaryimage"},"thumbnailUrl":"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/neues-forschungs-und-entwicklungsgebaeude-two.jpg","datePublished":"2024-01-22T12:53:03+00:00","dateModified":"2024-09-11T07:40:42+00:00","description":"Siamo lieti di poter condividere con voi una notizia entusiasmante: Il modernissimo Centro di Ricerca e Sviluppo LinMot \u00e8 stato completato con successo.","breadcrumb":{"@id":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/#primaryimage","url":"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/neues-forschungs-und-entwicklungsgebaeude-two.jpg","contentUrl":"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/01\/neues-forschungs-und-entwicklungsgebaeude-two.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/linmot.com\/it\/blog\/investire-nel-vostro-futuro-il-nuovo-centro-di-ricerca-e-sviluppo-linmot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/linmot.com\/it\/"},{"@type":"ListItem","position":2,"name":"Investire nel vostro futuro &#8211; Il nuovo centro di ricerca e sviluppo LinMot"}]},{"@type":"WebSite","@id":"https:\/\/linmot.com\/it\/#website","url":"https:\/\/linmot.com\/it\/","name":"LinMot e MagSpring - Italiano","description":"Motori lineari e sistemi di motori lineari di alta qualit\u00e0","publisher":{"@id":"https:\/\/linmot.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linmot.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/linmot.com\/it\/#organization","name":"NTI AG - LinMot & MagSpring","url":"https:\/\/linmot.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/linmot.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2022\/05\/linmot-social-share-logo.jpg","contentUrl":"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2022\/05\/linmot-social-share-logo.jpg","width":800,"height":500,"caption":"NTI AG - LinMot & MagSpring"},"image":{"@id":"https:\/\/linmot.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/pamoco-spa\/","https:\/\/www.youtube.com\/user\/LinMotEurope"]},{"@type":"Person","@id":"https:\/\/linmot.com\/it\/#\/schema\/person\/c38ac16ef20d42812ab8395e98452df0","name":"andreas","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e99f323d000f2404dd6db188993d585a3765965ba46a2313d331baea8a979d2e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e99f323d000f2404dd6db188993d585a3765965ba46a2313d331baea8a979d2e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e99f323d000f2404dd6db188993d585a3765965ba46a2313d331baea8a979d2e?s=96&d=mm&r=g","caption":"andreas"}}]}},"_links":{"self":[{"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/posts\/3269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/comments?post=3269"}],"version-history":[{"count":5,"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/posts\/3269\/revisions"}],"predecessor-version":[{"id":3628,"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/posts\/3269\/revisions\/3628"}],"wp:attachment":[{"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/media?parent=3269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/categories?post=3269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/tags?post=3269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}