{"id":220,"date":"2017-11-07T15:27:15","date_gmt":"2017-11-07T14:27:15","guid":{"rendered":"https:\/\/linmot.com\/?page_id=220"},"modified":"2024-07-08T11:11:31","modified_gmt":"2024-07-08T09:11:31","slug":"medicina-e-industria-farmaceutica","status":"publish","type":"page","link":"https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/","title":{"rendered":"Medicina e industria farmaceutica"},"content":{"rendered":"<p><strong>L\u2019ambito delle applicazioni per i dispositivi di trasmissione lineari nel settore medico e farmaceutico \u00e8 molto ampio.<\/strong><\/p>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-221\" src=\"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2017\/11\/LinMot-Solutions-Medical-Pharmaceutical-Industry.jpg\" alt=\"\" width=\"940\" height=\"300\" srcset=\"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2017\/11\/LinMot-Solutions-Medical-Pharmaceutical-Industry.jpg 940w, https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2017\/11\/LinMot-Solutions-Medical-Pharmaceutical-Industry-300x96.jpg 300w, https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2017\/11\/LinMot-Solutions-Medical-Pharmaceutical-Industry-768x245.jpg 768w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/>\n<p>Per la manipolazione dei campioni di sangue, il conteggio e il riempimento di pillole, o il confezionamento di farmaci particolari, i componenti LinMot garantiscono un elevato livello di dinamismo e precisione.<br \/>\nIl design igienico dei motori lineari permette di trattare in un contesto di massima igiene questi prodotti altamente sensibili, in conformit\u00e0 con le regolamentazioni relative agli ambienti sterili.<\/p>\n<p>I clienti traggono beneficio dalla nostra esperienza, potendo utilizzare soluzioni gi\u00e0 implementate nelle seguenti aree:<\/p>\n<div class=\"row\">\n<div class=\"col-sm-4\">\n<ul>\n<li>Postazioni di riempimento flessibili<\/li>\n<li>Misurazione e conteggio<\/li>\n<li>Inserimento<\/li>\n<li>Chiusure<\/li>\n<\/ul>\n<\/div>\n<div class=\"col-sm-4\">\n<ul>\n<li>Chiusure a pressione<\/li>\n<li>Imballaggio in confezioni di cartone<\/li>\n<li>Etichettatura<\/li>\n<li>Sistemi di prelievo e posizionamento<\/li>\n<\/ul>\n<\/div>\n<div class=\"col-sm-4\">\n<ul>\n<li>Manipolazione e pallettizzazione di prodotti<\/li>\n<li>Manipolazione di blister e vassoi<\/li>\n<li>Sistemi di confezionamento per blister e vassoi<\/li>\n<li>ecc.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>LinMot ha sviluppato moduli speciali in acciaio inossidabile per applicazioni nell&#8217;industria medica e farmaceutica. Progettati per gli ambienti pi\u00f9 difficili, i motori lineari compatti LinMot SSC sono realizzati in acciaio inox EN 1.4404\/AISI 316. Per evitare l&#8217;accumulo di sporcizia, i motori sono progettati senza spigoli, angoli, fori e collegamenti a vite inutili. Possono essere utilizzati in macchine e sistemi per la lavorazione degli alimenti o nell&#8217;industria farmaceutica. In questo modo, possono affrontare senza problemi ambienti estremamente difficili o corrosivi e possono essere puliti senza esitazione con tutti i detergenti standard del settore.<\/p>\n<p>Una panoramica di tutti i prodotti LinMot \u00e8 disponibile su questa pagina: <\/p>\n<p><a class=\"button\" href=\"\/it\/i-prodotti-di-linmot-e-magspring\/\">Alla panoramica dei prodotti<\/a><\/p>\n<hr \/>\n<div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"yumpu\" data-borlabs-cookie-content=\"PGlmcmFtZSB3aWR0aD0iOTQwcHgiIGhlaWdodD0iNzkzcHgiIHNyYz0iaHR0cHM6Ly93d3cueXVtcHUuY29tL2l0L2VtYmVkL3ZpZXcvNTk4dXNoTkNxUWlGRTFCNyIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbj0idHJ1ZSIgIGFsbG93dHJhbnNwYXJlbmN5PSJ0cnVlIj48L2lmcmFtZT4=\">\n<div class=\"brlbs-cmpnt-cb-preset-a\">\n<p class=\"brlbs-cmpnt-cb-description\">Stai visualizzando un contenuto segnaposto da <strong>Yumpu<\/strong>. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di notare che in questo modo si condividono i dati con provider di terze parti.<\/p>\n<div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Sblocca il contenuto<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Accetta il servizio richiesto e sblocca i contenuti<\/a> <\/div>\n<p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Ulteriori informazioni<\/a> <\/div>\n<\/div>\n<hr>\n<h2>Applicazioni realizzate nell\u2019industria medica e farmaceutica<\/h2>\n<div class=\"row download\">\n<div class=\"col-md-3\">\n<h4 class=\"download-title\">La lotta alla contraffazione dei farmaci<\/h4>\n<p class=\"bodytext\" align=\"justify\">Con oltre 6 miliardi di prodotti lavorati all\u2019anno e con la tecnologia di azionamento lineare leader di LinMot, le macchine di codifica Hicof uniche nel loro genere, sono all\u2019avanguardia nell\u2019anticontraffazione.<\/p>\n<p><a class=\"button\" href=\"\/it\/blog\/la-lotta-alla-contraffazione-dei-farmaci\/\">Maggiori informazioni<\/a><br \/>\n<\/div>\n<div class=\"col-md-2\">\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3296 size-full\" src=\"https:\/\/linmot.com\/wp-content\/uploads\/2022\/08\/fight-against-counterfeit-medications-application-report.jpg\" alt=\"\" width=\"220\" height=\"220\" \/><br \/>\n<\/div>\n<div class=\"col-md-2\">\n<\/div>\n<div class=\"col-md-3\">\n<h4 class=\"download-title\">Produzione farmaceutica in tempi di pandemia Covid 19<\/h4>\n<p class=\"bodytext\" align=\"justify\">Sistemi di riempimento e tappatura multiformato di Zellwag Pharmtech AG con motori di sollevamento e rotazione di precisione di LinMot.<\/p>\n<p><a class=\"button\" href=\"\/it\/blog\/produzione-farmaceutica-in-tempi-di-pandemia-covid-19\/\">Maggiori informazioni<\/a><br \/>\n<\/div>\n<div class=\"col-md-2\">\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3296 size-full\" src=\"https:\/\/linmot.com\/wp-content\/uploads\/2022\/08\/pharmaceutical-production-during-covid-19-application-report.jpg\" alt=\"\" width=\"220\" height=\"220\" \/><br \/>\n<\/div>\n<\/div>\n<div class=\"row download\">\n<div class=\"col-md-3\">\n<h4 class=\"download-title\">Sistemi LinMot in macchine farmaceutiche di AFAQ<\/h4>\n<p class=\"bodytext\" align=\"justify\">In qualit\u00e0 di azienda leader nella regione MENA (Medio Oriente e Nord Africa) per le macchine e le linee di produzione farmaceutiche, AFAQ si impegna a fondo per confrontare e selezionare i sistemi all\u2019avanguardia utilizzati nelle sue macchine (serie DropFill-SC per il riempimento e la chiusura dei colliri).<\/p>\n<p><a class=\"button\" href=\"\/it\/blog\/sistemi-linmot-in-macchine-farmaceutiche-di-afaq\/\">Maggiori informazioni<\/a><br \/>\n<\/div>\n<div class=\"col-md-2\">\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3296 size-full\" src=\"https:\/\/linmot.com\/wp-content\/uploads\/2022\/08\/afaq-pharmaceutical-machines-application-report.jpg\" alt=\"\" width=\"220\" height=\"220\" \/><br \/>\n<\/div>\n<div class=\"col-md-2\">\n<\/div>\n<div class=\"col-md-3\">\n<h4 class=\"download-title\">Motori lineari come polmoni artificiali per il test delle maschere<\/h4>\n<p class=\"bodytext\" align=\"justify\">Le maschere mediche bocca-naso possono contribuire a ridurre la diffusione del virus COVID-19. Lo confermano i test sistematici e riproducibili condotti dall&#8217;OTH di Regensburg utilizzando un simulatore polmonare che funziona con i motori lineari di LinMot. Questi ultimi hanno contribuito al fatto che i ricercatori sono stati in grado di creare il setup di prova in pochi giorni e di avviare la serie di test.<\/p>\n<p><a class=\"button\" href=\"\/it\/blog\/covid-19-motori-lineari-come-polmoni-artificiali-per-il-test-delle-maschere\/\">Maggiori informazioni<\/a><br \/>\n<\/div>\n<div class=\"col-md-2\">\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3297 size-full\" src=\"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/vorschau-covid-19-maskentests.jpg\" alt=\"\" width=\"220\" height=\"220\" \/><br \/>\n<\/div>\n<\/div>\n<div class=\"row download\">\n<div class=\"col-md-3\">\n<h4 class=\"download-title\">Le macchine di riempimento e sigillatura di Zellwag AG<\/h4>\n<p class=\"bodytext\" align=\"justify\">Dinamica nell&#8217;industria delle macchine di riempimento e di sigillatura. Dal 2002 la Zellwag AG si affida ai motori lineari per la costruzione delle sue macchine di riempimento e sigillatura completamente automatizzate per prodotti farmaceutici e cosmetici.<\/p>\n<p><a class=\"button\" href=\"\/it\/blog\/verso-le-stelle-e-oltre-le-macchine-di-riempimento-e-sigillatura-di-zellwag-ag\/\">Maggiori informazioni<\/a><br \/>\n<\/div>\n<div class=\"col-md-2\">\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3297 size-full\" src=\"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2022\/04\/zellwag-fuell-und-verschliessmaschinen.jpg\" alt=\"\" width=\"220\" height=\"220\" \/><br \/>\n<\/div>\n<div class=\"col-md-2\">\n<\/div>\n<div class=\"col-md-3\">\n<h4 class=\"download-title\">Spingersi oltre il limite con LinMot<\/h4>\n<p class=\"bodytext\" align=\"justify\">I motori lineari LinMot sono particolarmente adatti all&#8217;impiego nelle camere bianche farmaceutiche e sono pertanto dotati di un certificato corrispondente. Sono poco abrasivi, richiedono manutenzione solo a intervalli lunghi e sono facili da pulire. Ma questo non \u00e8 l&#8217;unico motivo per cui sono un componente indispensabile dei moderni impianti di produzione farmaceutica per il rinomato produttore svizzero di imballaggi primari Hoffmann Neopac AG.<\/p>\n<p><a class=\"button\" href=\"\/it\/blog\/spingersi-oltre-il-limite-con-linmot\/\">Maggiori informazioni<\/a><br \/>\n<\/div>\n<div class=\"col-md-2\">\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3297 size-full\" src=\"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2023\/02\/vorschau-tube-druecken.jpg\" alt=\"\" width=\"220\" height=\"220\" \/><br \/>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ambito delle applicazioni per i dispositivi di trasmissione lineari nel settore medico e farmaceutico \u00e8 molto ampio. Per la manipolazione dei campioni di sangue, il conteggio e il riempimento di pillole, o il confezionamento di farmaci particolari, i componenti LinMot garantiscono un elevato livello di dinamismo e precisione. Il design igienico dei motori lineari permette [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":8,"menu_order":74,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-220","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Medicale e farmaceutico- Dosaggio, conteggio, sigillatura | LinMot<\/title>\n<meta name=\"description\" content=\"Grazie al design igienico e alla tecnologia dei sensori integrata e calibrabile, le applicazioni nel settore medicale e farmaceutico con regolamenti per camere bianche possono essere elaborate in modo pulito.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medicale e farmaceutico- Dosaggio, conteggio, sigillatura | LinMot\" \/>\n<meta property=\"og:description\" content=\"Grazie al design igienico e alla tecnologia dei sensori integrata e calibrabile, le applicazioni nel settore medicale e farmaceutico con regolamenti per camere bianche possono essere elaborate in modo pulito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/\" \/>\n<meta property=\"og:site_name\" content=\"LinMot e MagSpring - Italiano\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-08T09:11:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2017\/11\/LinMot-Solutions-Medical-Pharmaceutical-Industry.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Medicale e farmaceutico- Dosaggio, conteggio, sigillatura | LinMot\" \/>\n<meta name=\"twitter:description\" content=\"Grazie al design igienico e alla tecnologia dei sensori integrata e calibrabile, le applicazioni nel settore medicale e farmaceutico con regolamenti per camere bianche possono essere elaborate in modo pulito.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2017\/11\/LinMot-Solutions-Medical-Pharmaceutical-Industry.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/soluzioni-industriali\\\/medicina-e-industria-farmaceutica\\\/\",\"url\":\"https:\\\/\\\/linmot.com\\\/it\\\/soluzioni-industriali\\\/medicina-e-industria-farmaceutica\\\/\",\"name\":\"Medicale e farmaceutico- Dosaggio, conteggio, sigillatura | LinMot\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/soluzioni-industriali\\\/medicina-e-industria-farmaceutica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/soluzioni-industriali\\\/medicina-e-industria-farmaceutica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/linmot.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/11\\\/LinMot-Solutions-Medical-Pharmaceutical-Industry.jpg\",\"datePublished\":\"2017-11-07T14:27:15+00:00\",\"dateModified\":\"2024-07-08T09:11:31+00:00\",\"description\":\"Grazie al design igienico e alla tecnologia dei sensori integrata e calibrabile, le applicazioni nel settore medicale e farmaceutico con regolamenti per camere bianche possono essere elaborate in modo pulito.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/soluzioni-industriali\\\/medicina-e-industria-farmaceutica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/linmot.com\\\/it\\\/soluzioni-industriali\\\/medicina-e-industria-farmaceutica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/soluzioni-industriali\\\/medicina-e-industria-farmaceutica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/linmot.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/11\\\/LinMot-Solutions-Medical-Pharmaceutical-Industry.jpg\",\"contentUrl\":\"https:\\\/\\\/linmot.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2017\\\/11\\\/LinMot-Solutions-Medical-Pharmaceutical-Industry.jpg\",\"width\":940,\"height\":300,\"caption\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/soluzioni-industriali\\\/medicina-e-industria-farmaceutica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/linmot.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soluzioni industriali\",\"item\":\"https:\\\/\\\/linmot.com\\\/it\\\/soluzioni-industriali\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Medicina e industria farmaceutica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/linmot.com\\\/it\\\/\",\"name\":\"LinMot e MagSpring - Italiano\",\"description\":\"Motori lineari e sistemi di motori lineari di alta qualit\u00e0\",\"publisher\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linmot.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#organization\",\"name\":\"NTI AG - LinMot & MagSpring\",\"url\":\"https:\\\/\\\/linmot.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/linmot.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/05\\\/linmot-social-share-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/linmot.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/05\\\/linmot-social-share-logo.jpg\",\"width\":800,\"height\":500,\"caption\":\"NTI AG - LinMot & MagSpring\"},\"image\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pamoco-spa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/LinMotEurope\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Medicale e farmaceutico- Dosaggio, conteggio, sigillatura | LinMot","description":"Grazie al design igienico e alla tecnologia dei sensori integrata e calibrabile, le applicazioni nel settore medicale e farmaceutico con regolamenti per camere bianche possono essere elaborate in modo pulito.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/","og_locale":"it_IT","og_type":"article","og_title":"Medicale e farmaceutico- Dosaggio, conteggio, sigillatura | LinMot","og_description":"Grazie al design igienico e alla tecnologia dei sensori integrata e calibrabile, le applicazioni nel settore medicale e farmaceutico con regolamenti per camere bianche possono essere elaborate in modo pulito.","og_url":"https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/","og_site_name":"LinMot e MagSpring - Italiano","article_modified_time":"2024-07-08T09:11:31+00:00","og_image":[{"width":940,"height":300,"url":"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2017\/11\/LinMot-Solutions-Medical-Pharmaceutical-Industry.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Medicale e farmaceutico- Dosaggio, conteggio, sigillatura | LinMot","twitter_description":"Grazie al design igienico e alla tecnologia dei sensori integrata e calibrabile, le applicazioni nel settore medicale e farmaceutico con regolamenti per camere bianche possono essere elaborate in modo pulito.","twitter_image":"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2017\/11\/LinMot-Solutions-Medical-Pharmaceutical-Industry.jpg","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/","url":"https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/","name":"Medicale e farmaceutico- Dosaggio, conteggio, sigillatura | LinMot","isPartOf":{"@id":"https:\/\/linmot.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/#primaryimage"},"image":{"@id":"https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/#primaryimage"},"thumbnailUrl":"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2017\/11\/LinMot-Solutions-Medical-Pharmaceutical-Industry.jpg","datePublished":"2017-11-07T14:27:15+00:00","dateModified":"2024-07-08T09:11:31+00:00","description":"Grazie al design igienico e alla tecnologia dei sensori integrata e calibrabile, le applicazioni nel settore medicale e farmaceutico con regolamenti per camere bianche possono essere elaborate in modo pulito.","breadcrumb":{"@id":"https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/#primaryimage","url":"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2017\/11\/LinMot-Solutions-Medical-Pharmaceutical-Industry.jpg","contentUrl":"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2017\/11\/LinMot-Solutions-Medical-Pharmaceutical-Industry.jpg","width":940,"height":300,"caption":""},{"@type":"BreadcrumbList","@id":"https:\/\/linmot.com\/it\/soluzioni-industriali\/medicina-e-industria-farmaceutica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/linmot.com\/it\/"},{"@type":"ListItem","position":2,"name":"Soluzioni industriali","item":"https:\/\/linmot.com\/it\/soluzioni-industriali\/"},{"@type":"ListItem","position":3,"name":"Medicina e industria farmaceutica"}]},{"@type":"WebSite","@id":"https:\/\/linmot.com\/it\/#website","url":"https:\/\/linmot.com\/it\/","name":"LinMot e MagSpring - Italiano","description":"Motori lineari e sistemi di motori lineari di alta qualit\u00e0","publisher":{"@id":"https:\/\/linmot.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linmot.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/linmot.com\/it\/#organization","name":"NTI AG - LinMot & MagSpring","url":"https:\/\/linmot.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/linmot.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2022\/05\/linmot-social-share-logo.jpg","contentUrl":"https:\/\/linmot.com\/it\/wp-content\/uploads\/sites\/4\/2022\/05\/linmot-social-share-logo.jpg","width":800,"height":500,"caption":"NTI AG - LinMot & MagSpring"},"image":{"@id":"https:\/\/linmot.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/pamoco-spa\/","https:\/\/www.youtube.com\/user\/LinMotEurope"]}]}},"_links":{"self":[{"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/pages\/220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/comments?post=220"}],"version-history":[{"count":18,"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/pages\/220\/revisions"}],"predecessor-version":[{"id":3519,"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/pages\/220\/revisions\/3519"}],"up":[{"embeddable":true,"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/pages\/8"}],"wp:attachment":[{"href":"https:\/\/linmot.com\/it\/wp-json\/wp\/v2\/media?parent=220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}