{"id":3976,"date":"2024-02-12T11:29:40","date_gmt":"2024-02-12T10:29:40","guid":{"rendered":"https:\/\/linmot.com\/de\/?page_id=3976"},"modified":"2026-02-02T17:37:38","modified_gmt":"2026-02-02T16:37:38","slug":"linearmodule-dm03","status":"publish","type":"page","link":"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/","title":{"rendered":"Linearmodule DM03"},"content":{"rendered":"<p align=\"justify\"><strong>Die speziell f\u00fcr vertikale Anwendungen entwickelten Linearmodule der Serie DM03 bieten einen grossen Hubbereich in einem besonders schlanken Geh\u00e4use. Dadurch k\u00f6nnen DM03 Linearmodule platzsparend und dicht nebeneinander angeordnet werden. Das schlanke Geh\u00e4use enth\u00e4lt bereits eine neue, st\u00e4rkere MagSpring\u00ae-Generation f\u00fcr den vertikalen Lastausgleich und kann optional durch einen hochaufl\u00f6senden Positionssensor im Modul oder einen Kraftsensor an der Front erg\u00e4nzt werden.<\/strong><\/p>\n<hr \/>\n<div class=\"row\">\n<div class=\"col-sm-2\">\n<p><a class=\"button\" href=\"#details\">1. Details<\/a><\/p>\n<\/div>\n<div class=\"col-sm-1\">\n<\/div>\n<div class=\"col-sm-2\">\n<p><a class=\"button\" href=\"#videos\">2. Videos<\/a><\/p>\n<\/div>\n<div class=\"col-sm-1\">\n<\/div>\n<div class=\"col-sm-2\">\n<p><a class=\"button\" href=\"#anwendung\">3. Anwendung<\/a><\/p>\n<\/div>\n<div class=\"col-sm-1\">\n<\/div>\n<div class=\"col-sm-2\">\n<p><a class=\"button\" href=\"#kontakt\">4. Kontakt<\/a><\/p>\n<\/div>\n<\/div>\n<hr \/>\n<h2 id=\"details\">1. Details<\/h2>\n<div class=\"row\">\n<div class=\"col-md-7\">\n<p align=\"justify\">Der ausgekl\u00fcgelte mechanische Aufbau der DM0x-Linearmodul-Familie verhindert grosse Auflagekr\u00e4fte zwischen Motor und L\u00e4ufer, was zu einer sehr hohen Lebensdauer bei minimalem Wartungsaufwand des Motors f\u00fchrt. Dar\u00fcber hinaus verf\u00fcgen diese Linearmodule bereits \u00fcber ein integriertes, gewichtsoptimiertes F\u00fchrungssystem zur Aufnahme von Querkr\u00e4ften und zur einfachen Montage der Lastmasse.<\/p>\n<p align=\"justify\">Insgesamt stehen dem Anwender f\u00fcnf verschiedene Baugr\u00f6ssen zur Verf\u00fcgung. Die Motorenpalette von 23x80F-HP bis 48x240F-HP bietet Maximalkr\u00e4fte von 67 N bis 1020 N. Diese hochdynamischen Linearmodule lassen in Sachen Dynamik keine W\u00fcnsche offen und erreichen problemlos Beschleunigungen von 50 m\/s2 und Geschwindigkeiten von bis zu 5 m\/s.<\/p>\n<ul>\n<li>Sehr schlanke Bauweise<\/li>\n<li>Ideal f\u00fcr vertikale Anwendungen<\/li>\n<li>Integrierter Lastausgleich durch neue MagSpring-Generation bis 170 N<\/li>\n<li>Optimierte bewegte Masse f\u00fcr hohe Dynamik und Beschleunigungen \u00fcber 50 m\/s2<\/li>\n<li>Minimaler Montageabstand f\u00fcr die Aneinanderreihung mehrerer Module<\/li>\n<li>6 Baugr\u00f6ssen mit Maximalkr\u00e4ften bis zu 1020 N<\/li>\n<li>Absoluter Positionssensor f\u00fcr eine Wiederholgenauigkeit von +\/- 0.001 mm optional<\/li>\n<li>Kraftsensor f\u00fcr Genauigkeit von bis zu 0,5 % optional<\/li>\n<li>Kombinierbar im LinMot Modulbaukasten und mit allen LinMot Produkten, z.B. als Z-Achse f\u00fcr LinMot Semi-Gantry und Gantry<\/li>\n<\/ul>\n<p><a class=\"btn btn-active\" href=\"\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/Teaserflyer_DM03_WEB_DE.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Der Flyer zum Download (PDF)<\/a><\/p>\n<h3>Integrierter Vertikallastausgleich<\/h3>\n<p align=\"justify\">Parallel zum Linearmotor eingebaut, dient die MagSpring als intelligenter Lastausgleich f\u00fcr die auftretende Gewichtskraft. Mit der neuen MagSpring-Generation kann die Gewichtskompensation stufenweise von 11 N bis maximal 170 N gew\u00e4hlt werden. Durch die feine Abstufung der MagSpring k\u00f6nnen Applikationen so ausgelegt werden, dass sich die Position des Linearmotors im Fehlerfall nicht selbstst\u00e4ndig ver\u00e4ndert oder beim Abschalten automatisch eine Referenzposition erreicht wird.<\/p>\n<p><a class=\"btn btn-active\" href=\"\/de\/produkte\/magspring\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mehr zu MagSpring<\/a><\/p>\n<\/div>\n<div class=\"col-md-5\">\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4873 size-full\" src=\"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/dm03-produktseite.png\" alt=\"DM03\" width=\"576\" height=\"911\" srcset=\"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/dm03-produktseite.png 576w, https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/dm03-produktseite-190x300.png 190w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/>\n<\/div>\n<\/div>\n<h3>Semi-Gantry<\/h3>\n<p align=\"justify\">Die DM03 Linearmodule bieten ein breites Portfolio an Maximalkr\u00e4ften und Hubl\u00e4ngen. Dank dieser Kraft- und Gr\u00f6ssenvielfalt sowie der Modularit\u00e4t k\u00f6nnen sie mit allen anderen LinMot Modulen kombiniert werden. Durch die Kombinationen k\u00f6nnen verschiedene Strukturen, wie Semi-Gantry, Gantry und Pick-and-Place (YZ) realisiert werden. Vorteile der Semi-Gantry Konstruktionen:<\/p>\n<div class=\"row\">\n<div class=\"col-md-7\">\n<ul>\n<li>Effiziente Nutzung des Maschinenraums<\/li>\n<li>Im Vergleich zu Gantry entf\u00e4llt eine zweite F\u00fchrung mit Antrieb<\/li>\n<li>Auch mit mehreren Auslegern bzw. Wagen m\u00f6glich<\/li>\n<li>LinMot Baukasten erlaubt die Kombination aller Module untereinander<\/li>\n<li>Schleppkettenkonzept f\u00fcr alle Achsen im LinMot Baukasten enthalten<\/li>\n<\/ul>\n<\/div>\n<div class=\"col-md-5\">\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4900 size-full\" src=\"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/linearmodule-dm03-semi-gantry.jpg\" alt=\"DM03\" width=\"607\" height=\"200\" srcset=\"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/linearmodule-dm03-semi-gantry.jpg 607w, https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/linearmodule-dm03-semi-gantry-300x99.jpg 300w\" sizes=\"auto, (max-width: 607px) 100vw, 607px\" \/>\n<\/div>\n<\/div>\n<div class=\"row\"><\/div>\n<h2 id=\"videos\">2. Videos<\/h2>\n<h4 class=\"download-title\">Linearmodul DM03<\/h4>\n<div class=\"row download\">\n<div class=\"col-md-7\">\n<p class=\"bodytext\" align=\"justify\">Das Video zeigt ein DM03 Linearmodul mit einer Hubl\u00e4nge von 695 mm. Durch den langen Hub, den integrierten Lastausgleich und die Dynamik des Linearmotors eignet sich dieses Linearmodul besonders f\u00fcr vertikale Anwendungen mit langen H\u00fcben, kurzen Prozesszeiten und der Forderung nach niedrigen Energiekosten.<\/p>\n<p class=\"bodytext\" align=\"justify\">Anwendungsbeispiel: Bei vielen Anwendungen, wie z.B. der Etikettierung, werden unterschiedlich grosse Pakete auf einem F\u00f6rderband verarbeitet. Je nach Paketgr\u00f6sse m\u00fcssen unterschiedliche H\u00fcbe zur\u00fcckgelegt werden, ausserdem soll die Etikettierung m\u00f6glichst schnell erfolgen. Das DM03 Linearmodul beweist gerade bei solchen Hochgeschwindigkeitsprozessen seine herausragende Dynamik und legt einen Hub von 695 mm in nur 300 ms zur\u00fcck. Durch die integrierte Lastkompensation \u00abschwebt\u00bb das Modul zudem schwerelos und der Linearmotor kann seine volle Dynamik f\u00fcr die eigentliche Anwendung nutzen.<\/p>\n<\/div>\n<div class=\"col-md-5\">\n<div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"youtube-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSB0aXRsZT0iWW91VHViZSB2aWRlbyBwbGF5ZXIiIHNyYz0iaHR0cHM6Ly93d3cueW91dHViZS1ub2Nvb2tpZS5jb20vZW1iZWQvdTFzY0xtMDBLR1E\/c2k9N2NiLWtDUDJrZXNiOW9xOCIgd2lkdGg9IjM5NCIgaGVpZ2h0PSIyMjAiIGZyYW1lYm9yZGVyPSIwIiBhbGxvd2Z1bGxzY3JlZW49ImFsbG93ZnVsbHNjcmVlbiI+PC9pZnJhbWU+\">\n<div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-youtube\">\n<div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/linmot.com\/de\/wp-content\/uploads\/borlabs-cookie\/2\/yt_u1scLm00KGQ_hqdefault.jpg')\"><\/div>\n<div class=\"brlbs-cmpnt-cb-main\">\n<div class=\"brlbs-cmpnt-cb-play-button\"><\/div>\n<div class=\"brlbs-cmpnt-cb-content\">\n<p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>YouTube<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p>\n<p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div>\n<div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n<h3>Energie- und Kosteneinsparungen<\/h3>\n<p align=\"justify\">Um das Einsparpotential zu demonstrieren, wurde die oben beschriebene Applikation aufgebaut, bei der das Linearmodul DM03 einen Hub von 695 mm in ca. 300 ms zur\u00fccklegt. Der j\u00e4hrliche Energieverbrauch dieser Anwendung betr\u00e4gt 405 kWh. Im Vergleich dazu w\u00fcrde ein 32 mm Pneumatikzylinder 12.000 kWh verbrauchen. Dies entspricht einem Faktor 30 beim Energieverbrauch und somit einer Einsparung von 2.900 Euro pro Modul und Jahr.<\/p>\n<p><a class=\"btn btn-active\" href=\"https:\/\/linmot.com\/de\/branchen\/ersatz-von-pneumatik-durch-industrielle-linearmotoren\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mehr zur Energieeffizienz<\/a><\/p>\n<h3 id=\"anwendung\">3. Anwendung<\/h3>\n<div class=\"row download\">\n<div class=\"col-md-7\">\n<h4 class=\"download-title\">Auf die Achse, fertig, hoch!<\/h4>\n<p class=\"bodytext\" align=\"justify\">Wie schafft man es eigentlich, Etikettierprozesse von unterschiedlich grossen Paketen m\u00f6glichst schnell und sicher zu realisieren? Und vor allem, wie schafft man das bei vertikalen Anwendungen, bei denen die Gewichtskraft der Achse und der Last st\u00e4ndig auf den Prozess einwirkt? Unser Artikel in LINEAR gibt Ihnen die Antwort.<\/p>\n<p><a class=\"button\" href=\"\/de\/blog\/auf-die-achse-fertig-hoch-linearmodul-dm03\/\">Zum Artikel<\/a><br \/>\n<\/div>\n<div class=\"col-md-5\">\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4906\" src=\"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/auf-die-achse-teaserbild.jpg\" alt=\"\" width=\"560\" height=\"300\" srcset=\"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/auf-die-achse-teaserbild.jpg 560w, https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/auf-die-achse-teaserbild-300x161.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/>\n<\/div>\n<\/div>\n<h2 id=\"kontakt\">4. Kontakt<\/h2>\n<div class=\"row download\">\n<div class=\"col-md-6\">\n<h4 class=\"download-title\">Fragen zu den Linearmodulen DM03?<\/h4>\n<p class=\"bodytext\">Wir stehen Ihnen f\u00fcr Ihre Fragen gerne zur Verf\u00fcgung.<br \/>\nMelden Sie sich hierf\u00fcr \u00fcber das folgende Formular bei uns oder rufen Sie uns an unter:<\/p>\n<p class=\"bodytext\">Tel: +49 (0)201 858940 0<\/p>\n<p class=\"bodytext\">Das LinMot-Team<\/p>\n<\/div>\n<div class=\"col-md-1\">\n<\/div>\n<div class=\"col-md-5\">\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1617-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"1617\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/3976#wpcf7-f1617-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1617\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1617-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<label> Ihr Name<br>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<br>\n<label> Ihre Firma<br>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-company\" \/><\/span> <\/label>\n<br>\n<label> Postleitzahl<br>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-plz\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"your-plz\" \/><\/span> <\/label>\n<br>\n<label> Land<br>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-country\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-country\" \/><\/span> <\/label>\n<br>\n<label> Telefonnummer<br>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-telephone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"your-telephone\" \/><\/span> <\/label>\n<br>\n<label> E-Mail-Adresse<br>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<br>\n<label> Ihre Frage<br>\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<br>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Senden\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die speziell f\u00fcr vertikale Anwendungen entwickelten Linearmodule der Serie DM03 bieten einen grossen Hubbereich in einem besonders schlanken Geh\u00e4use. Dadurch k\u00f6nnen DM03 Linearmodule platzsparend und dicht nebeneinander angeordnet werden. Das schlanke Geh\u00e4use enth\u00e4lt bereits eine neue, st\u00e4rkere MagSpring\u00ae-Generation f\u00fcr den vertikalen Lastausgleich und kann optional durch einen hochaufl\u00f6senden Positionssensor im Modul oder einen Kraftsensor an [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":44,"menu_order":26,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3976","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Linearmodule DM03 | LinMot<\/title>\n<meta name=\"description\" content=\"Die speziell f\u00fcr vertikale Anwendungen entwickelten Linearmodule der Serie DM03 bieten einen grossen Hubbereich in einem besonders schlanken Geh\u00e4use.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Linearmodule DM03 | Linear Motion Technology Leader | LinMot\" \/>\n<meta property=\"og:description\" content=\"Die speziell f\u00fcr vertikale Anwendungen entwickelten Linearmodule der Serie DM03 bieten einen grossen Hubbereich in einem besonders schlanken Geh\u00e4use.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/\" \/>\n<meta property=\"og:site_name\" content=\"LinMot &amp; MagSpring - Deutsch\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T16:37:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/dm03-produktseite.png\" \/>\n\t<meta property=\"og:image:width\" content=\"576\" \/>\n\t<meta property=\"og:image:height\" content=\"911\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Linearmodule DM03 | Linear Motion Technology Leader | LinMot\" \/>\n<meta name=\"twitter:description\" content=\"Die speziell f\u00fcr vertikale Anwendungen entwickelten Linearmodule der Serie DM03 bieten einen grossen Hubbereich in einem besonders schlanken Geh\u00e4use.\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/linmot.com\\\/de\\\/produkte\\\/linearfuehrungen-linearmodule\\\/linearmodule-dm03\\\/\",\"url\":\"https:\\\/\\\/linmot.com\\\/de\\\/produkte\\\/linearfuehrungen-linearmodule\\\/linearmodule-dm03\\\/\",\"name\":\"Linearmodule DM03 | LinMot\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/de\\\/produkte\\\/linearfuehrungen-linearmodule\\\/linearmodule-dm03\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/de\\\/produkte\\\/linearfuehrungen-linearmodule\\\/linearmodule-dm03\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/linmot.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/02\\\/dm03-produktseite.png\",\"datePublished\":\"2024-02-12T10:29:40+00:00\",\"dateModified\":\"2026-02-02T16:37:38+00:00\",\"description\":\"Die speziell f\u00fcr vertikale Anwendungen entwickelten Linearmodule der Serie DM03 bieten einen grossen Hubbereich in einem besonders schlanken Geh\u00e4use.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/de\\\/produkte\\\/linearfuehrungen-linearmodule\\\/linearmodule-dm03\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/linmot.com\\\/de\\\/produkte\\\/linearfuehrungen-linearmodule\\\/linearmodule-dm03\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/linmot.com\\\/de\\\/produkte\\\/linearfuehrungen-linearmodule\\\/linearmodule-dm03\\\/#primaryimage\",\"url\":\"https:\\\/\\\/linmot.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/02\\\/dm03-produktseite.png\",\"contentUrl\":\"https:\\\/\\\/linmot.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/02\\\/dm03-produktseite.png\",\"width\":576,\"height\":911,\"caption\":\"Linearmodul DM03\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/linmot.com\\\/de\\\/produkte\\\/linearfuehrungen-linearmodule\\\/linearmodule-dm03\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"LinMot\",\"item\":\"https:\\\/\\\/linmot.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/linmot.com\\\/de\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Linearf\u00fchrungen \\\/ Linearmodule\",\"item\":\"https:\\\/\\\/linmot.com\\\/de\\\/produkte\\\/linearfuehrungen-linearmodule\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Linearmodule DM03\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/linmot.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/linmot.com\\\/de\\\/\",\"name\":\"LinMot & MagSpring - Industrielle Linearmotoren\",\"description\":\"Hochwertigen Linearmotoren und Linearmotorsystemen\",\"publisher\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/linmot.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/linmot.com\\\/de\\\/#organization\",\"name\":\"NTI AG - LinMot & MagSpring\",\"url\":\"https:\\\/\\\/linmot.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/linmot.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/linmot.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/social-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/linmot.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/social-logo.jpg\",\"width\":800,\"height\":500,\"caption\":\"NTI AG - LinMot & MagSpring\"},\"image\":{\"@id\":\"https:\\\/\\\/linmot.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/nti-ag-linmot-magspring\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/LinMotEurope\",\"https:\\\/\\\/www.xing.com\\\/pages\\\/linmot-magspring\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Linearmodule DM03 | LinMot","description":"Die speziell f\u00fcr vertikale Anwendungen entwickelten Linearmodule der Serie DM03 bieten einen grossen Hubbereich in einem besonders schlanken Geh\u00e4use.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/","og_locale":"de_DE","og_type":"article","og_title":"Linearmodule DM03 | Linear Motion Technology Leader | LinMot","og_description":"Die speziell f\u00fcr vertikale Anwendungen entwickelten Linearmodule der Serie DM03 bieten einen grossen Hubbereich in einem besonders schlanken Geh\u00e4use.","og_url":"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/","og_site_name":"LinMot &amp; MagSpring - Deutsch","article_modified_time":"2026-02-02T16:37:38+00:00","og_image":[{"width":576,"height":911,"url":"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/dm03-produktseite.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Linearmodule DM03 | Linear Motion Technology Leader | LinMot","twitter_description":"Die speziell f\u00fcr vertikale Anwendungen entwickelten Linearmodule der Serie DM03 bieten einen grossen Hubbereich in einem besonders schlanken Geh\u00e4use.","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/","url":"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/","name":"Linearmodule DM03 | LinMot","isPartOf":{"@id":"https:\/\/linmot.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/#primaryimage"},"image":{"@id":"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/#primaryimage"},"thumbnailUrl":"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/dm03-produktseite.png","datePublished":"2024-02-12T10:29:40+00:00","dateModified":"2026-02-02T16:37:38+00:00","description":"Die speziell f\u00fcr vertikale Anwendungen entwickelten Linearmodule der Serie DM03 bieten einen grossen Hubbereich in einem besonders schlanken Geh\u00e4use.","breadcrumb":{"@id":"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/#primaryimage","url":"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/dm03-produktseite.png","contentUrl":"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2024\/02\/dm03-produktseite.png","width":576,"height":911,"caption":"Linearmodul DM03"},{"@type":"BreadcrumbList","@id":"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/linearmodule-dm03\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"LinMot","item":"https:\/\/linmot.com\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/linmot.com\/de\/produkte\/"},{"@type":"ListItem","position":3,"name":"Linearf\u00fchrungen \/ Linearmodule","item":"https:\/\/linmot.com\/de\/produkte\/linearfuehrungen-linearmodule\/"},{"@type":"ListItem","position":4,"name":"Linearmodule DM03"}]},{"@type":"WebSite","@id":"https:\/\/linmot.com\/de\/#website","url":"https:\/\/linmot.com\/de\/","name":"LinMot & MagSpring - Industrielle Linearmotoren","description":"Hochwertigen Linearmotoren und Linearmotorsystemen","publisher":{"@id":"https:\/\/linmot.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/linmot.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/linmot.com\/de\/#organization","name":"NTI AG - LinMot & MagSpring","url":"https:\/\/linmot.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/linmot.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2022\/01\/social-logo.jpg","contentUrl":"https:\/\/linmot.com\/de\/wp-content\/uploads\/sites\/2\/2022\/01\/social-logo.jpg","width":800,"height":500,"caption":"NTI AG - LinMot & MagSpring"},"image":{"@id":"https:\/\/linmot.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/nti-ag-linmot-magspring","https:\/\/www.youtube.com\/user\/LinMotEurope","https:\/\/www.xing.com\/pages\/linmot-magspring"]}]}},"_links":{"self":[{"href":"https:\/\/linmot.com\/de\/wp-json\/wp\/v2\/pages\/3976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/linmot.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/linmot.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/linmot.com\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/linmot.com\/de\/wp-json\/wp\/v2\/comments?post=3976"}],"version-history":[{"count":61,"href":"https:\/\/linmot.com\/de\/wp-json\/wp\/v2\/pages\/3976\/revisions"}],"predecessor-version":[{"id":6292,"href":"https:\/\/linmot.com\/de\/wp-json\/wp\/v2\/pages\/3976\/revisions\/6292"}],"up":[{"embeddable":true,"href":"https:\/\/linmot.com\/de\/wp-json\/wp\/v2\/pages\/44"}],"wp:attachment":[{"href":"https:\/\/linmot.com\/de\/wp-json\/wp\/v2\/media?parent=3976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}